{"id":4180,"date":"2024-05-14T09:22:23","date_gmt":"2024-05-14T09:22:23","guid":{"rendered":"https:\/\/bastardsknives.com\/?post_type=product&#038;p=4180"},"modified":"2024-08-20T12:52:09","modified_gmt":"2024-08-20T12:52:09","slug":"cobre-sanmai-carbono-cobre-cobre-sanmai","status":"publish","type":"product","link":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/","title":{"rendered":"Cobre SanMai (carbono\/cobre)"},"content":{"rendered":"<p>Explore la calidad excepcional de nuestras Placas de Cobre SanMai (carbono\/cobre), compuestas por capas de 1.2842 y cobre en un patr\u00f3n SanMai. Con superficie paja al fuego, estas placas de 5 capas ofrecen soldaduras de capa SuperClean, grano muy fino y alta sujeci\u00f3n del canto. Fabricadas con un proceso de producci\u00f3n fiable, estas placas garantizan un rendimiento confiable en una variedad de aplicaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Placas de Cobre SanMai (carbono\/cobre): Compuesto 1.2842\/cobre, 5 capas, patr\u00f3n SanMai. Superficie paja al fuego, soldaduras precisas.<\/p>\n","protected":false},"featured_media":4183,"template":"","meta":[],"product_brand":[],"product_cat":[234,761],"product_tag":[],"class_list":["post-4180","product","type-product","status-publish","has-post-thumbnail","product_cat-balbachdamast","product_cat-carbono","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cobre SanMai (carbono\/cobre) - Bastards Knives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cobre SanMai (carbono\/cobre) - Bastards Knives\" \/>\n<meta property=\"og:description\" content=\"Placas de Cobre SanMai (carbono\/cobre): Compuesto 1.2842\/cobre, 5 capas, patr\u00f3n SanMai. Superficie paja al fuego, soldaduras precisas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/\" \/>\n<meta property=\"og:site_name\" content=\"Bastards Knives\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T12:52:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/\",\"url\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/\",\"name\":\"Cobre SanMai (carbono\/cobre) - Bastards Knives\",\"isPartOf\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg\",\"datePublished\":\"2024-05-14T09:22:23+00:00\",\"dateModified\":\"2024-08-20T12:52:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage\",\"url\":\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg\",\"contentUrl\":\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bastardsknives.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/bastardsknives.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cobre SanMai (carbono\/cobre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bastardsknives.com\/es\/#website\",\"url\":\"https:\/\/bastardsknives.com\/es\/\",\"name\":\"Bastards Knives\",\"description\":\"Bastards Knives | Viviendo al filo\",\"publisher\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bastardsknives.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bastardsknives.com\/es\/#organization\",\"name\":\"Bastards Knives\",\"url\":\"https:\/\/bastardsknives.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bastardsknives.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2022\/07\/Logoprod1.png\",\"contentUrl\":\"https:\/\/bastardsknives.com\/wp-content\/uploads\/2022\/07\/Logoprod1.png\",\"width\":284,\"height\":122,\"caption\":\"Bastards Knives\"},\"image\":{\"@id\":\"https:\/\/bastardsknives.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cobre SanMai (carbono\/cobre) - Bastards Knives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/","og_locale":"es_ES","og_type":"article","og_title":"Cobre SanMai (carbono\/cobre) - Bastards Knives","og_description":"Placas de Cobre SanMai (carbono\/cobre): Compuesto 1.2842\/cobre, 5 capas, patr\u00f3n SanMai. Superficie paja al fuego, soldaduras precisas.","og_url":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/","og_site_name":"Bastards Knives","article_modified_time":"2024-08-20T12:52:09+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/","url":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/","name":"Cobre SanMai (carbono\/cobre) - Bastards Knives","isPartOf":{"@id":"https:\/\/bastardsknives.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage"},"image":{"@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage"},"thumbnailUrl":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg","datePublished":"2024-05-14T09:22:23+00:00","dateModified":"2024-08-20T12:52:09+00:00","breadcrumb":{"@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#primaryimage","url":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg","contentUrl":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2024\/05\/copper-sanmai-carboncopper.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/bastardsknives.com\/es\/producto\/cobre-sanmai-carbono-cobre-cobre-sanmai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bastardsknives.com\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/bastardsknives.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cobre SanMai (carbono\/cobre)"}]},{"@type":"WebSite","@id":"https:\/\/bastardsknives.com\/es\/#website","url":"https:\/\/bastardsknives.com\/es\/","name":"Bastards Knives","description":"Bastards Knives | Viviendo al filo","publisher":{"@id":"https:\/\/bastardsknives.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bastardsknives.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bastardsknives.com\/es\/#organization","name":"Bastards Knives","url":"https:\/\/bastardsknives.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bastardsknives.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2022\/07\/Logoprod1.png","contentUrl":"https:\/\/bastardsknives.com\/wp-content\/uploads\/2022\/07\/Logoprod1.png","width":284,"height":122,"caption":"Bastards Knives"},"image":{"@id":"https:\/\/bastardsknives.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/product\/4180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/media\/4183"}],"wp:attachment":[{"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/media?parent=4180"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/product_brand?post=4180"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/product_cat?post=4180"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bastardsknives.com\/es\/wp-json\/wp\/v2\/product_tag?post=4180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}